{"id":171,"date":"2025-08-28T09:36:38","date_gmt":"2025-08-28T09:36:38","guid":{"rendered":"https:\/\/demo2wpopal.b-cdn.net\/eyecazi\/?page_id=171"},"modified":"2026-04-30T11:27:33","modified_gmt":"2026-04-30T08:27:33","slug":"aboutus","status":"publish","type":"page","link":"https:\/\/bestoptic.ro\/en\/despre-noi\/","title":{"rendered":"About us"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"171\" class=\"elementor elementor-171\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-346dc6c e-flex e-con-boxed e-con e-parent\" data-id=\"346dc6c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-44681ab e-con-full e-flex e-con e-child\" data-id=\"44681ab\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4b8ee28 animated-fast elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-invisible elementor-widget elementor-widget-icon-list\" data-id=\"4b8ee28\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;opal-move-up&quot;}\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eyecazi-icon- eyecazi-icon-icon-cross\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Cu pasiune pentru vederea ta<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c33838f elementor-widget__width-initial animated-fast elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"c33838f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;opal-move-left&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Tu e\u0219ti punctul <br> nostru de focus<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9593594 e-flex e-con-boxed e-con e-parent\" data-id=\"9593594\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-cf224c9 e-con-full e-flex e-con e-child\" data-id=\"cf224c9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e64a70f elementor-widget__width-initial elementor-widget-mobile__width-inherit animated-fast elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"e64a70f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;opal-move-up&quot;,&quot;_animation_delay&quot;:100}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><h6 class=\"elementor-image-box-title\">Consulta\u021bii complete,<br>g\u00e2ndite \u00een jurul t\u0103u<\/h6><p class=\"elementor-image-box-description\">Prime\u0219ti prescrip\u021bii f\u0103cute doar pe baza unor investiga\u021bii detaliate, cu timp dedicat \u021bie, explica\u021bii clare \u0219i consiliere \u00een alegerea ramelor \u0219i lentilelor. Fiecare ochi este privit ca unic, iar solu\u021bia vizual\u0103 este construit\u0103 pentru felul \u00een care \u00ee\u021bi folose\u0219ti vederea zi de zi.\n<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-520a441 e-con-full e-flex e-con e-child\" data-id=\"520a441\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b9a8e89 elementor-widget__width-initial elementor-widget-mobile__width-inherit animated-fast elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"b9a8e89\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;opal-move-up&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><h6 class=\"elementor-image-box-title\">Tehnologie de top \u0219i o echip\u0103 <br>complet\u0103 pentru ochii t\u0103i<\/h6><p class=\"elementor-image-box-description\">M\u0103sur\u0103m cu iProfiler \u0219i iTerminal ZEISS, mont\u0103m ochelarii \u00een propriul laborator computerizat \u0219i lucr\u0103m al\u0103turi de medici oftalmologi \u0219i exper\u021bi \u00een lentile de contact, keratoconus \u0219i ortokeratologie. Ai \u00een acela\u0219i loc tot ce ai nevoie pentru ochi s\u0103n\u0103to\u0219i \u0219i vedere clar\u0103.\n<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3f29f07 e-grid e-con-boxed e-con e-parent\" data-id=\"3f29f07\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-b23a17b e-con-full animated-fast e-flex elementor-invisible e-con e-child\" data-id=\"b23a17b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;opal-move-up&quot;}\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ae73064 e-con-full animated-fast e-flex elementor-invisible e-con e-child\" data-id=\"ae73064\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;opal-move-up&quot;,&quot;animation_delay&quot;:100}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f0aa0dd elementor-widget elementor-widget-counter\" data-id=\"f0aa0dd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"18\" data-from-value=\"0\" data-delimiter=\",\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\">+<\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9639239 elementor-widget elementor-widget-icon-box\" data-id=\"9639239\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h6 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tAni de experien\u021b\u0103 \u00een optometrie\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h6>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f62f652 e-con-full animated-fast e-flex elementor-invisible e-con e-child\" data-id=\"f62f652\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;opal-move-up&quot;,&quot;animation_delay&quot;:200}\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1d8984f e-con-full animated-fast e-flex elementor-invisible e-con e-child\" data-id=\"1d8984f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;opal-move-up&quot;,&quot;animation_delay&quot;:300}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-52e86d7 elementor-widget elementor-widget-counter\" data-id=\"52e86d7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"5\" data-from-value=\"0\" data-delimiter=\",\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\">\/5<\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b1b643f elementor-widget elementor-widget-icon-box\" data-id=\"b1b643f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h6 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tNota dat\u0103 de pacien\u021bii no\u0219tri experien\u021bei\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h6>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-62ba369 e-con-full e-flex e-con e-parent\" data-id=\"62ba369\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;background_motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;background_motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;background_motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:2,&quot;sizes&quot;:[]},&quot;background_motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;laptop&quot;,&quot;tablet_extra&quot;,&quot;tablet&quot;],&quot;background_motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}}}\">\n\t\t<div class=\"elementor-element elementor-element-227cefc e-con-full e-flex e-con e-child\" data-id=\"227cefc\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-afdcafd e-flex e-con-boxed e-con e-child\" data-id=\"afdcafd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fd2510e animated-fast elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-invisible elementor-widget elementor-widget-icon-list\" data-id=\"fd2510e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;opal-move-right&quot;}\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eyecazi-icon- eyecazi-icon-icon-cross\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">De ce noi?<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-846c6ba elementor-widget__width-initial animated-fast elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"846c6ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;opal-move-right&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"> Diferen\u021bele care chiar conteaz\u0103 pentru tine\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f880d30 e-flex e-con-boxed e-con e-child\" data-id=\"f880d30\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-4ac65e7 e-con-full e-flex e-con e-child\" data-id=\"4ac65e7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-2148203 e-con-full animated-fast e-flex elementor-invisible e-con e-child\" data-id=\"2148203\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;opal-move-up&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-890a962 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"890a962\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256c0 136.967-111.033 248-248 248S8 392.967 8 256 119.033 8 256 8s248 111.033 248 248zM227.314 387.314l184-184c6.248-6.248 6.248-16.379 0-22.627l-22.627-22.627c-6.248-6.249-16.379-6.249-22.628 0L216 308.118l-70.059-70.059c-6.248-6.248-16.379-6.248-22.628 0l-22.627 22.627c-6.248 6.248-6.248 16.379 0 22.627l104 104c6.249 6.249 16.379 6.249 22.628.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Consulta\u021bii detaliate \u0219i complete<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-28e7c1d elementor-widget elementor-widget-text-editor\" data-id=\"28e7c1d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Fiecare vizit\u0103 \u00eenseamn\u0103 timp rezervat \u021bie, investiga\u021bii pas cu pas \u0219i o imagine clar\u0103 asupra vederii \u0219i s\u0103n\u0103t\u0103\u021bii ochilor t\u0103i.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ff77ce3 e-con-full animated-fast e-flex elementor-invisible e-con e-child\" data-id=\"ff77ce3\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;opal-move-up&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-39f80b3 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"39f80b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256c0 136.967-111.033 248-248 248S8 392.967 8 256 119.033 8 256 8s248 111.033 248 248zM227.314 387.314l184-184c6.248-6.248 6.248-16.379 0-22.627l-22.627-22.627c-6.248-6.249-16.379-6.249-22.628 0L216 308.118l-70.059-70.059c-6.248-6.248-16.379-6.248-22.628 0l-22.627 22.627c-6.248 6.248-6.248 16.379 0 22.627l104 104c6.249 6.249 16.379 6.249 22.628.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Personalizare cu tehnologii moderne<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-542d3e8 elementor-widget elementor-widget-text-editor\" data-id=\"542d3e8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">M\u0103sur\u0103m parametrii individuali ai ochilor t\u0103i \u0219i corel\u0103m totul cu rama aleas\u0103, astfel \u00eenc\u00e2t lentilele s\u0103 fie f\u0103cute pentru ochii t\u0103i.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d3089f2 e-con-full e-flex e-con e-child\" data-id=\"d3089f2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-d8bb7e2 e-con-full animated-fast e-flex elementor-invisible e-con e-child\" data-id=\"d8bb7e2\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;opal-move-up&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1087b83 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"1087b83\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256c0 136.967-111.033 248-248 248S8 392.967 8 256 119.033 8 256 8s248 111.033 248 248zM227.314 387.314l184-184c6.248-6.248 6.248-16.379 0-22.627l-22.627-22.627c-6.248-6.249-16.379-6.249-22.628 0L216 308.118l-70.059-70.059c-6.248-6.248-16.379-6.248-22.628 0l-22.627 22.627c-6.248 6.248-6.248 16.379 0 22.627l104 104c6.249 6.249 16.379 6.249 22.628.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Laborator propriu de montaj<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bec7e0e elementor-widget elementor-widget-text-editor\" data-id=\"bec7e0e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Ochelarii t\u0103i sunt monta\u021bi \u0219i verifica\u021bi intern, cu control pe fiecare etap\u0103. Tu \u00eei ridici gata de purtat, cu montaj corect \u0219i garan\u021bie a calit\u0103\u021bii.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d20218f e-con-full animated-fast e-flex elementor-invisible e-con e-child\" data-id=\"d20218f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;opal-move-up&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4062885 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"4062885\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256c0 136.967-111.033 248-248 248S8 392.967 8 256 119.033 8 256 8s248 111.033 248 248zM227.314 387.314l184-184c6.248-6.248 6.248-16.379 0-22.627l-22.627-22.627c-6.248-6.249-16.379-6.249-22.628 0L216 308.118l-70.059-70.059c-6.248-6.248-16.379-6.248-22.628 0l-22.627 22.627c-6.248 6.248-6.248 16.379 0 22.627l104 104c6.249 6.249 16.379 6.249 22.628.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Tratamente avansate pentru cazuri speciale<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7b88b9d elementor-widget elementor-widget-text-editor\" data-id=\"7b88b9d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Dac\u0103 ai nevoie de solu\u021bii mai complexe, g\u0103se\u0219ti aici expertiz\u0103 \u0219i op\u021biuni moderne, adaptate specific ochilor t\u0103i.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-051fb50 e-flex e-con-boxed e-con e-parent\" data-id=\"051fb50\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-4476ab7 e-con-full e-flex e-con e-child\" data-id=\"4476ab7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-5ad8772 e-con-full e-flex e-con e-child\" data-id=\"5ad8772\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-722a68d e-con-full e-flex e-con e-child\" data-id=\"722a68d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8c3b2b4 animated-fast elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-invisible elementor-widget elementor-widget-icon-list\" data-id=\"8c3b2b4\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;opal-move-left&quot;}\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eyecazi-icon- eyecazi-icon-icon-cross\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Cunoa\u0219te echipa<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f97aec0 elementor-widget__width-initial animated-fast elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"f97aec0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;opal-move-left&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ochii t\u0103i, <br>\u00een grija noastr\u0103<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5447e64 e-con-full e-flex e-con e-child\" data-id=\"5447e64\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b8e60e2 elementor-widget__width-initial animated-fast elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"b8e60e2\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;opal-move-right&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Speciali\u0219ti care lucreaz\u0103 \u00eempreun\u0103 pentru ca tu s\u0103 ai o vedere clar\u0103 \u0219i \u00eengrijit\u0103 pe termen lung.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-da29d6f elementor-widget__width-inherit animated-fast teambox-layout-1 elementor-invisible elementor-widget elementor-widget-eyecazi-team-box\" data-id=\"da29d6f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;opal-move-up&quot;}\" data-widget_type=\"eyecazi-team-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"elementor-teambox-item-wrapper\">\n            <div class=\"d-grid\">\n                                    <div class=\"grid-item elementor-teambox-item\">\n\n                        \n                        <div class=\"team-content\">\n                            <div class=\"team-caption\">\n                                                                    <div class=\"team-job\">Optometrist &amp; Specialist \u00een lentile de contact<\/div>\n                                \n                                                                    <h6 class=\"team-name\">Gyuri Bodi <\/h6>\n                                                            <\/div>\n\n                                                            <div class=\"team-image-wrapper\">\n                                                <div class=\"team-image\">\n                <img fetchpriority=\"high\" decoding=\"async\" width=\"1260\" height=\"1260\" src=\"https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/Gyuri.png\" class=\"attachment-full size-full wp-image-10564\" alt=\"\" srcset=\"https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/Gyuri.png 1260w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/Gyuri-300x300.png 300w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/Gyuri-1024x1024.png 1024w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/Gyuri-150x150.png 150w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/Gyuri-768x768.png 768w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/Gyuri-800x800.png 800w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/Gyuri-1000x1000.png 1000w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/Gyuri-100x100.png 100w\" sizes=\"(max-width: 1260px) 100vw, 1260px\" \/>            <\/div>\n                                                    <div class=\"team-box-socials-wrapper\">\n            <div class=\"team-icon-socials\">\n                <ul>\n                                                                                                                                                                                                                    <\/ul>\n            <\/div>\n        <\/div>\n                                        <\/div>\n                            \n                            <div class=\"team-description\">\n                                \n                                        <div class=\"more-link-wrap\">\n            <a class=\"more-link effect-button-link\" href=\"#\">\n                                    <span class=\"elementor-button-content-wrapper content-wrapper\">\n                    <span class=\"elementor-button-text\">\n                        <span>View Profile<\/span>\n                    <\/span>\n                    <span class=\"button-icon\">\n                        <i class=\"eyecazi-icon-arrow-right\" aria-hidden=\"true\"><\/i>\n                    <\/span>\n                <\/span>\n                                    <span class=\"elementor-button-content-wrapper content-wrapper-hover\">\n                    <span class=\"elementor-button-text\">\n                        <span>View Profile<\/span>\n                    <\/span>\n                    <span class=\"button-icon\">\n                        <i class=\"eyecazi-icon-arrow-right\" aria-hidden=\"true\"><\/i>\n                    <\/span>\n                <\/span>\n                            <\/a>\n        <\/div>\n    \n                                                            <\/div>\n                        <\/div>\n                    <\/div>\n                                    <div class=\"grid-item elementor-teambox-item\">\n\n                        \n                        <div class=\"team-content\">\n                            <div class=\"team-caption\">\n                                                                    <div class=\"team-job\">Optometrist &amp; Specialist \u00een lentile de contact<\/div>\n                                \n                                                                    <h6 class=\"team-name\">Alina Petric<\/h6>\n                                                            <\/div>\n\n                                                            <div class=\"team-image-wrapper\">\n                                                <div class=\"team-image\">\n                <img decoding=\"async\" width=\"1260\" height=\"1260\" src=\"https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/Alina-Petric.png\" class=\"attachment-full size-full wp-image-10601\" alt=\"\" srcset=\"https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/Alina-Petric.png 1260w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/Alina-Petric-300x300.png 300w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/Alina-Petric-1024x1024.png 1024w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/Alina-Petric-150x150.png 150w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/Alina-Petric-768x768.png 768w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/Alina-Petric-800x800.png 800w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/Alina-Petric-1000x1000.png 1000w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/Alina-Petric-100x100.png 100w\" sizes=\"(max-width: 1260px) 100vw, 1260px\" \/>            <\/div>\n                                                    <div class=\"team-box-socials-wrapper\">\n            <div class=\"team-icon-socials\">\n                <ul>\n                                                                        <li class=\"social\">\n                                <a href=\"https:\/\/www.facebook.com\/opalwordpress\">\n                                    <i class=\"eyecazi-icon-facebook\"><\/i>\n                                <\/a>\n                            <\/li>\n                                                                                                <li class=\"social\">\n                                <a href=\"https:\/\/twitter.com\/opalwordpress\">\n                                    <i class=\"eyecazi-icon-twitter-x\"><\/i>\n                                <\/a>\n                            <\/li>\n                                                                                                <li class=\"social\">\n                                <a href=\"https:\/\/www.instagram.com\/user\/WPOpalTheme\">\n                                    <i class=\"eyecazi-icon-instagram\"><\/i>\n                                <\/a>\n                            <\/li>\n                                                                                                <li class=\"social\">\n                                <a href=\"https:\/\/vn.linkedin.com\/company\/wpopal\">\n                                    <i class=\"eyecazi-icon-linkedin\"><\/i>\n                                <\/a>\n                            <\/li>\n                                                            <\/ul>\n            <\/div>\n        <\/div>\n                                        <\/div>\n                            \n                            <div class=\"team-description\">\n                                \n                                        <div class=\"more-link-wrap\">\n            <a class=\"more-link effect-button-link\" href=\"https:\/\/demo2wpopal.b-cdn.net\/eyecazi\/our-doctors-01\/dr-harsy-backley\/\">\n                                    <span class=\"elementor-button-content-wrapper content-wrapper\">\n                    <span class=\"elementor-button-text\">\n                        <span>View Profile<\/span>\n                    <\/span>\n                    <span class=\"button-icon\">\n                        <i class=\"eyecazi-icon-arrow-right\" aria-hidden=\"true\"><\/i>\n                    <\/span>\n                <\/span>\n                                    <span class=\"elementor-button-content-wrapper content-wrapper-hover\">\n                    <span class=\"elementor-button-text\">\n                        <span>View Profile<\/span>\n                    <\/span>\n                    <span class=\"button-icon\">\n                        <i class=\"eyecazi-icon-arrow-right\" aria-hidden=\"true\"><\/i>\n                    <\/span>\n                <\/span>\n                            <\/a>\n        <\/div>\n    \n                                                            <\/div>\n                        <\/div>\n                    <\/div>\n                                    <div class=\"grid-item elementor-teambox-item\">\n\n                        \n                        <div class=\"team-content\">\n                            <div class=\"team-caption\">\n                                                                    <div class=\"team-job\">Optometrist &amp; Specialist \u00een lentile de contact<\/div>\n                                \n                                                                    <h6 class=\"team-name\">Manuela Moldovan<\/h6>\n                                                            <\/div>\n\n                                                            <div class=\"team-image-wrapper\">\n                                                <div class=\"team-image\">\n                <img decoding=\"async\" width=\"1260\" height=\"1260\" src=\"https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/Manuela-Moldovan.png\" class=\"attachment-full size-full wp-image-10599\" alt=\"\" srcset=\"https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/Manuela-Moldovan.png 1260w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/Manuela-Moldovan-300x300.png 300w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/Manuela-Moldovan-1024x1024.png 1024w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/Manuela-Moldovan-150x150.png 150w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/Manuela-Moldovan-768x768.png 768w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/Manuela-Moldovan-800x800.png 800w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/Manuela-Moldovan-1000x1000.png 1000w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/Manuela-Moldovan-100x100.png 100w\" sizes=\"(max-width: 1260px) 100vw, 1260px\" \/>            <\/div>\n                                                    <div class=\"team-box-socials-wrapper\">\n            <div class=\"team-icon-socials\">\n                <ul>\n                                                                        <li class=\"social\">\n                                <a href=\"https:\/\/www.facebook.com\/opalwordpress\">\n                                    <i class=\"eyecazi-icon-facebook\"><\/i>\n                                <\/a>\n                            <\/li>\n                                                                                                <li class=\"social\">\n                                <a href=\"https:\/\/twitter.com\/opalwordpress\">\n                                    <i class=\"eyecazi-icon-twitter-x\"><\/i>\n                                <\/a>\n                            <\/li>\n                                                                                                <li class=\"social\">\n                                <a href=\"https:\/\/www.instagram.com\/user\/WPOpalTheme\">\n                                    <i class=\"eyecazi-icon-instagram\"><\/i>\n                                <\/a>\n                            <\/li>\n                                                                                                <li class=\"social\">\n                                <a href=\"https:\/\/vn.linkedin.com\/company\/wpopal\">\n                                    <i class=\"eyecazi-icon-linkedin\"><\/i>\n                                <\/a>\n                            <\/li>\n                                                            <\/ul>\n            <\/div>\n        <\/div>\n                                        <\/div>\n                            \n                            <div class=\"team-description\">\n                                \n                                        <div class=\"more-link-wrap\">\n            <a class=\"more-link effect-button-link\" href=\"https:\/\/demo2wpopal.b-cdn.net\/eyecazi\/our-doctors-01\/dr-nick-leng\/\">\n                                    <span class=\"elementor-button-content-wrapper content-wrapper\">\n                    <span class=\"elementor-button-text\">\n                        <span>View Profile<\/span>\n                    <\/span>\n                    <span class=\"button-icon\">\n                        <i class=\"eyecazi-icon-arrow-right\" aria-hidden=\"true\"><\/i>\n                    <\/span>\n                <\/span>\n                                    <span class=\"elementor-button-content-wrapper content-wrapper-hover\">\n                    <span class=\"elementor-button-text\">\n                        <span>View Profile<\/span>\n                    <\/span>\n                    <span class=\"button-icon\">\n                        <i class=\"eyecazi-icon-arrow-right\" aria-hidden=\"true\"><\/i>\n                    <\/span>\n                <\/span>\n                            <\/a>\n        <\/div>\n    \n                                                            <\/div>\n                        <\/div>\n                    <\/div>\n                                    <div class=\"grid-item elementor-teambox-item\">\n\n                        \n                        <div class=\"team-content\">\n                            <div class=\"team-caption\">\n                                                                    <div class=\"team-job\">Optometrist &amp; Specialist \u00een lentile de contact<\/div>\n                                \n                                                                    <h6 class=\"team-name\">Ioana Negurici<\/h6>\n                                                            <\/div>\n\n                                                            <div class=\"team-image-wrapper\">\n                                                <div class=\"team-image\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"1260\" height=\"1260\" src=\"https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/Ioana.jpg\" class=\"attachment-full size-full wp-image-10598\" alt=\"\" srcset=\"https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/Ioana.jpg 1260w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/Ioana-300x300.jpg 300w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/Ioana-1024x1024.jpg 1024w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/Ioana-150x150.jpg 150w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/Ioana-768x768.jpg 768w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/Ioana-800x800.jpg 800w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/Ioana-1000x1000.jpg 1000w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/Ioana-100x100.jpg 100w\" sizes=\"(max-width: 1260px) 100vw, 1260px\" \/>            <\/div>\n                                                    <div class=\"team-box-socials-wrapper\">\n            <div class=\"team-icon-socials\">\n                <ul>\n                                                                        <li class=\"social\">\n                                <a href=\"https:\/\/www.facebook.com\/opalwordpress\">\n                                    <i class=\"eyecazi-icon-facebook\"><\/i>\n                                <\/a>\n                            <\/li>\n                                                                                                <li class=\"social\">\n                                <a href=\"https:\/\/twitter.com\/opalwordpress\">\n                                    <i class=\"eyecazi-icon-twitter-x\"><\/i>\n                                <\/a>\n                            <\/li>\n                                                                                                <li class=\"social\">\n                                <a href=\"https:\/\/www.instagram.com\/user\/WPOpalTheme\">\n                                    <i class=\"eyecazi-icon-instagram\"><\/i>\n                                <\/a>\n                            <\/li>\n                                                                                                <li class=\"social\">\n                                <a href=\"https:\/\/vn.linkedin.com\/company\/wpopal\">\n                                    <i class=\"eyecazi-icon-linkedin\"><\/i>\n                                <\/a>\n                            <\/li>\n                                                            <\/ul>\n            <\/div>\n        <\/div>\n                                        <\/div>\n                            \n                            <div class=\"team-description\">\n                                \n                                        <div class=\"more-link-wrap\">\n            <a class=\"more-link effect-button-link\" href=\"https:\/\/demo2wpopal.b-cdn.net\/eyecazi\/our-doctors-01\/dr-nick-leng\/\">\n                                    <span class=\"elementor-button-content-wrapper content-wrapper\">\n                    <span class=\"elementor-button-text\">\n                        <span>View Profile<\/span>\n                    <\/span>\n                    <span class=\"button-icon\">\n                        <i class=\"eyecazi-icon-arrow-right\" aria-hidden=\"true\"><\/i>\n                    <\/span>\n                <\/span>\n                                    <span class=\"elementor-button-content-wrapper content-wrapper-hover\">\n                    <span class=\"elementor-button-text\">\n                        <span>View Profile<\/span>\n                    <\/span>\n                    <span class=\"button-icon\">\n                        <i class=\"eyecazi-icon-arrow-right\" aria-hidden=\"true\"><\/i>\n                    <\/span>\n                <\/span>\n                            <\/a>\n        <\/div>\n    \n                                                            <\/div>\n                        <\/div>\n                    <\/div>\n                                    <div class=\"grid-item elementor-teambox-item\">\n\n                        \n                        <div class=\"team-content\">\n                            <div class=\"team-caption\">\n                                                                    <div class=\"team-job\">Optometrist &amp; Specialist \u00een lentile de contact<\/div>\n                                \n                                                                    <h6 class=\"team-name\">Cristina Dr\u0103gu\u0219anu<\/h6>\n                                                            <\/div>\n\n                                                            <div class=\"team-image-wrapper\">\n                                                <div class=\"team-image\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"1260\" height=\"1260\" src=\"https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/All-copy.png\" class=\"attachment-full size-full wp-image-10602\" alt=\"\" srcset=\"https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/All-copy.png 1260w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/All-copy-300x300.png 300w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/All-copy-1024x1024.png 1024w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/All-copy-150x150.png 150w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/All-copy-768x768.png 768w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/All-copy-800x800.png 800w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/All-copy-1000x1000.png 1000w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/All-copy-100x100.png 100w\" sizes=\"(max-width: 1260px) 100vw, 1260px\" \/>            <\/div>\n                                                    <div class=\"team-box-socials-wrapper\">\n            <div class=\"team-icon-socials\">\n                <ul>\n                                                                        <li class=\"social\">\n                                <a href=\"https:\/\/www.facebook.com\/opalwordpress\">\n                                    <i class=\"eyecazi-icon-facebook\"><\/i>\n                                <\/a>\n                            <\/li>\n                                                                                                <li class=\"social\">\n                                <a href=\"https:\/\/twitter.com\/opalwordpress\">\n                                    <i class=\"eyecazi-icon-twitter-x\"><\/i>\n                                <\/a>\n                            <\/li>\n                                                                                                <li class=\"social\">\n                                <a href=\"https:\/\/www.instagram.com\/user\/WPOpalTheme\">\n                                    <i class=\"eyecazi-icon-instagram\"><\/i>\n                                <\/a>\n                            <\/li>\n                                                                                                <li class=\"social\">\n                                <a href=\"https:\/\/vn.linkedin.com\/company\/wpopal\">\n                                    <i class=\"eyecazi-icon-linkedin\"><\/i>\n                                <\/a>\n                            <\/li>\n                                                            <\/ul>\n            <\/div>\n        <\/div>\n                                        <\/div>\n                            \n                            <div class=\"team-description\">\n                                \n                                        <div class=\"more-link-wrap\">\n            <a class=\"more-link effect-button-link\" href=\"#\">\n                                    <span class=\"elementor-button-content-wrapper content-wrapper\">\n                    <span class=\"elementor-button-text\">\n                        <span>View Profile<\/span>\n                    <\/span>\n                    <span class=\"button-icon\">\n                        <i class=\"eyecazi-icon-arrow-right\" aria-hidden=\"true\"><\/i>\n                    <\/span>\n                <\/span>\n                                    <span class=\"elementor-button-content-wrapper content-wrapper-hover\">\n                    <span class=\"elementor-button-text\">\n                        <span>View Profile<\/span>\n                    <\/span>\n                    <span class=\"button-icon\">\n                        <i class=\"eyecazi-icon-arrow-right\" aria-hidden=\"true\"><\/i>\n                    <\/span>\n                <\/span>\n                            <\/a>\n        <\/div>\n    \n                                                            <\/div>\n                        <\/div>\n                    <\/div>\n                                    <div class=\"grid-item elementor-teambox-item\">\n\n                        \n                        <div class=\"team-content\">\n                            <div class=\"team-caption\">\n                                                                    <div class=\"team-job\">Optometrist &amp; Specialist \u00een lentile de contact<\/div>\n                                \n                                                                    <h6 class=\"team-name\">Ana Maria Mih\u0103il\u0103<\/h6>\n                                                            <\/div>\n\n                                                            <div class=\"team-image-wrapper\">\n                                                <div class=\"team-image\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"1260\" height=\"1260\" src=\"https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/BestOptic_Tean10-1.jpg\" class=\"attachment-full size-full wp-image-11412\" alt=\"\" srcset=\"https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/BestOptic_Tean10-1.jpg 1260w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/BestOptic_Tean10-1-300x300.jpg 300w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/BestOptic_Tean10-1-1024x1024.jpg 1024w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/BestOptic_Tean10-1-150x150.jpg 150w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/BestOptic_Tean10-1-768x768.jpg 768w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/BestOptic_Tean10-1-800x800.jpg 800w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/BestOptic_Tean10-1-1000x1000.jpg 1000w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/BestOptic_Tean10-1-100x100.jpg 100w\" sizes=\"(max-width: 1260px) 100vw, 1260px\" \/>            <\/div>\n                                                    <div class=\"team-box-socials-wrapper\">\n            <div class=\"team-icon-socials\">\n                <ul>\n                                                                        <li class=\"social\">\n                                <a href=\"https:\/\/www.facebook.com\/opalwordpress\">\n                                    <i class=\"eyecazi-icon-facebook\"><\/i>\n                                <\/a>\n                            <\/li>\n                                                                                                <li class=\"social\">\n                                <a href=\"https:\/\/twitter.com\/opalwordpress\">\n                                    <i class=\"eyecazi-icon-twitter-x\"><\/i>\n                                <\/a>\n                            <\/li>\n                                                                                                <li class=\"social\">\n                                <a href=\"https:\/\/www.instagram.com\/user\/WPOpalTheme\">\n                                    <i class=\"eyecazi-icon-instagram\"><\/i>\n                                <\/a>\n                            <\/li>\n                                                                                                <li class=\"social\">\n                                <a href=\"https:\/\/vn.linkedin.com\/company\/wpopal\">\n                                    <i class=\"eyecazi-icon-linkedin\"><\/i>\n                                <\/a>\n                            <\/li>\n                                                            <\/ul>\n            <\/div>\n        <\/div>\n                                        <\/div>\n                            \n                            <div class=\"team-description\">\n                                \n                                        <div class=\"more-link-wrap\">\n            <a class=\"more-link effect-button-link\" href=\"https:\/\/demo2wpopal.b-cdn.net\/eyecazi\/our-doctors-01\/dr-nick-leng\/\">\n                                    <span class=\"elementor-button-content-wrapper content-wrapper\">\n                    <span class=\"elementor-button-text\">\n                        <span>View Profile<\/span>\n                    <\/span>\n                    <span class=\"button-icon\">\n                        <i class=\"eyecazi-icon-arrow-right\" aria-hidden=\"true\"><\/i>\n                    <\/span>\n                <\/span>\n                                    <span class=\"elementor-button-content-wrapper content-wrapper-hover\">\n                    <span class=\"elementor-button-text\">\n                        <span>View Profile<\/span>\n                    <\/span>\n                    <span class=\"button-icon\">\n                        <i class=\"eyecazi-icon-arrow-right\" aria-hidden=\"true\"><\/i>\n                    <\/span>\n                <\/span>\n                            <\/a>\n        <\/div>\n    \n                                                            <\/div>\n                        <\/div>\n                    <\/div>\n                                    <div class=\"grid-item elementor-teambox-item\">\n\n                        \n                        <div class=\"team-content\">\n                            <div class=\"team-caption\">\n                                                                    <div class=\"team-job\">Optometrist <\/div>\n                                \n                                                                    <h6 class=\"team-name\">Alexandra Petcu<\/h6>\n                                                            <\/div>\n\n                                                            <div class=\"team-image-wrapper\">\n                                                <div class=\"team-image\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"1260\" height=\"1260\" src=\"https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/BestOptic_Team8.png\" class=\"attachment-full size-full wp-image-10592\" alt=\"\" srcset=\"https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/BestOptic_Team8.png 1260w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/BestOptic_Team8-300x300.png 300w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/BestOptic_Team8-1024x1024.png 1024w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/BestOptic_Team8-150x150.png 150w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/BestOptic_Team8-768x768.png 768w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/BestOptic_Team8-800x800.png 800w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/BestOptic_Team8-1000x1000.png 1000w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/BestOptic_Team8-100x100.png 100w\" sizes=\"(max-width: 1260px) 100vw, 1260px\" \/>            <\/div>\n                                                    <div class=\"team-box-socials-wrapper\">\n            <div class=\"team-icon-socials\">\n                <ul>\n                                                                        <li class=\"social\">\n                                <a href=\"https:\/\/www.facebook.com\/opalwordpress\">\n                                    <i class=\"eyecazi-icon-facebook\"><\/i>\n                                <\/a>\n                            <\/li>\n                                                                                                <li class=\"social\">\n                                <a href=\"https:\/\/twitter.com\/opalwordpress\">\n                                    <i class=\"eyecazi-icon-twitter-x\"><\/i>\n                                <\/a>\n                            <\/li>\n                                                                                                <li class=\"social\">\n                                <a href=\"https:\/\/www.instagram.com\/user\/WPOpalTheme\">\n                                    <i class=\"eyecazi-icon-instagram\"><\/i>\n                                <\/a>\n                            <\/li>\n                                                                                                <li class=\"social\">\n                                <a href=\"https:\/\/vn.linkedin.com\/company\/wpopal\">\n                                    <i class=\"eyecazi-icon-linkedin\"><\/i>\n                                <\/a>\n                            <\/li>\n                                                            <\/ul>\n            <\/div>\n        <\/div>\n                                        <\/div>\n                            \n                            <div class=\"team-description\">\n                                \n                                        <div class=\"more-link-wrap\">\n            <a class=\"more-link effect-button-link\" href=\"https:\/\/demo2wpopal.b-cdn.net\/eyecazi\/our-doctors-01\/dr-nick-leng\/\">\n                                    <span class=\"elementor-button-content-wrapper content-wrapper\">\n                    <span class=\"elementor-button-text\">\n                        <span>View Profile<\/span>\n                    <\/span>\n                    <span class=\"button-icon\">\n                        <i class=\"eyecazi-icon-arrow-right\" aria-hidden=\"true\"><\/i>\n                    <\/span>\n                <\/span>\n                                    <span class=\"elementor-button-content-wrapper content-wrapper-hover\">\n                    <span class=\"elementor-button-text\">\n                        <span>View Profile<\/span>\n                    <\/span>\n                    <span class=\"button-icon\">\n                        <i class=\"eyecazi-icon-arrow-right\" aria-hidden=\"true\"><\/i>\n                    <\/span>\n                <\/span>\n                            <\/a>\n        <\/div>\n    \n                                                            <\/div>\n                        <\/div>\n                    <\/div>\n                                    <div class=\"grid-item elementor-teambox-item\">\n\n                        \n                        <div class=\"team-content\">\n                            <div class=\"team-caption\">\n                                                                    <div class=\"team-job\">Optician<\/div>\n                                \n                                                                    <h6 class=\"team-name\">Olimpia Vila<\/h6>\n                                                            <\/div>\n\n                                                            <div class=\"team-image-wrapper\">\n                                                <div class=\"team-image\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"1260\" height=\"1260\" src=\"https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/BestOptic_Team5.png\" class=\"attachment-full size-full wp-image-10589\" alt=\"\" srcset=\"https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/BestOptic_Team5.png 1260w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/BestOptic_Team5-300x300.png 300w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/BestOptic_Team5-1024x1024.png 1024w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/BestOptic_Team5-150x150.png 150w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/BestOptic_Team5-768x768.png 768w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/BestOptic_Team5-800x800.png 800w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/BestOptic_Team5-1000x1000.png 1000w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/BestOptic_Team5-100x100.png 100w\" sizes=\"(max-width: 1260px) 100vw, 1260px\" \/>            <\/div>\n                                                    <div class=\"team-box-socials-wrapper\">\n            <div class=\"team-icon-socials\">\n                <ul>\n                                                                        <li class=\"social\">\n                                <a href=\"https:\/\/www.facebook.com\/opalwordpress\">\n                                    <i class=\"eyecazi-icon-facebook\"><\/i>\n                                <\/a>\n                            <\/li>\n                                                                                                <li class=\"social\">\n                                <a href=\"https:\/\/twitter.com\/opalwordpress\">\n                                    <i class=\"eyecazi-icon-twitter-x\"><\/i>\n                                <\/a>\n                            <\/li>\n                                                                                                <li class=\"social\">\n                                <a href=\"https:\/\/www.instagram.com\/user\/WPOpalTheme\">\n                                    <i class=\"eyecazi-icon-instagram\"><\/i>\n                                <\/a>\n                            <\/li>\n                                                                                                <li class=\"social\">\n                                <a href=\"https:\/\/vn.linkedin.com\/company\/wpopal\">\n                                    <i class=\"eyecazi-icon-linkedin\"><\/i>\n                                <\/a>\n                            <\/li>\n                                                            <\/ul>\n            <\/div>\n        <\/div>\n                                        <\/div>\n                            \n                            <div class=\"team-description\">\n                                \n                                        <div class=\"more-link-wrap\">\n            <a class=\"more-link effect-button-link\" href=\"#\">\n                                    <span class=\"elementor-button-content-wrapper content-wrapper\">\n                    <span class=\"elementor-button-text\">\n                        <span>View Profile<\/span>\n                    <\/span>\n                    <span class=\"button-icon\">\n                        <i class=\"eyecazi-icon-arrow-right\" aria-hidden=\"true\"><\/i>\n                    <\/span>\n                <\/span>\n                                    <span class=\"elementor-button-content-wrapper content-wrapper-hover\">\n                    <span class=\"elementor-button-text\">\n                        <span>View Profile<\/span>\n                    <\/span>\n                    <span class=\"button-icon\">\n                        <i class=\"eyecazi-icon-arrow-right\" aria-hidden=\"true\"><\/i>\n                    <\/span>\n                <\/span>\n                            <\/a>\n        <\/div>\n    \n                                                            <\/div>\n                        <\/div>\n                    <\/div>\n                                    <div class=\"grid-item elementor-teambox-item\">\n\n                        \n                        <div class=\"team-content\">\n                            <div class=\"team-caption\">\n                                                                    <div class=\"team-job\">Consultant v\u00e2nz\u0103ri<\/div>\n                                \n                                                                    <h6 class=\"team-name\">Rebeca Movileanu<\/h6>\n                                                            <\/div>\n\n                                                            <div class=\"team-image-wrapper\">\n                                                <div class=\"team-image\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"1260\" height=\"1260\" src=\"https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/BestOptic_Team4.png\" class=\"attachment-full size-full wp-image-10588\" alt=\"\" srcset=\"https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/BestOptic_Team4.png 1260w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/BestOptic_Team4-300x300.png 300w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/BestOptic_Team4-1024x1024.png 1024w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/BestOptic_Team4-150x150.png 150w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/BestOptic_Team4-768x768.png 768w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/BestOptic_Team4-800x800.png 800w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/BestOptic_Team4-1000x1000.png 1000w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/BestOptic_Team4-100x100.png 100w\" sizes=\"(max-width: 1260px) 100vw, 1260px\" \/>            <\/div>\n                                                    <div class=\"team-box-socials-wrapper\">\n            <div class=\"team-icon-socials\">\n                <ul>\n                                                                        <li class=\"social\">\n                                <a href=\"https:\/\/www.facebook.com\/opalwordpress\">\n                                    <i class=\"eyecazi-icon-facebook\"><\/i>\n                                <\/a>\n                            <\/li>\n                                                                                                <li class=\"social\">\n                                <a href=\"https:\/\/twitter.com\/opalwordpress\">\n                                    <i class=\"eyecazi-icon-twitter-x\"><\/i>\n                                <\/a>\n                            <\/li>\n                                                                                                <li class=\"social\">\n                                <a href=\"https:\/\/www.instagram.com\/user\/WPOpalTheme\">\n                                    <i class=\"eyecazi-icon-instagram\"><\/i>\n                                <\/a>\n                            <\/li>\n                                                                                                <li class=\"social\">\n                                <a href=\"https:\/\/vn.linkedin.com\/company\/wpopal\">\n                                    <i class=\"eyecazi-icon-linkedin\"><\/i>\n                                <\/a>\n                            <\/li>\n                                                            <\/ul>\n            <\/div>\n        <\/div>\n                                        <\/div>\n                            \n                            <div class=\"team-description\">\n                                \n                                        <div class=\"more-link-wrap\">\n            <a class=\"more-link effect-button-link\" href=\"#\">\n                                    <span class=\"elementor-button-content-wrapper content-wrapper\">\n                    <span class=\"elementor-button-text\">\n                        <span>View Profile<\/span>\n                    <\/span>\n                    <span class=\"button-icon\">\n                        <i class=\"eyecazi-icon-arrow-right\" aria-hidden=\"true\"><\/i>\n                    <\/span>\n                <\/span>\n                                    <span class=\"elementor-button-content-wrapper content-wrapper-hover\">\n                    <span class=\"elementor-button-text\">\n                        <span>View Profile<\/span>\n                    <\/span>\n                    <span class=\"button-icon\">\n                        <i class=\"eyecazi-icon-arrow-right\" aria-hidden=\"true\"><\/i>\n                    <\/span>\n                <\/span>\n                            <\/a>\n        <\/div>\n    \n                                                            <\/div>\n                        <\/div>\n                    <\/div>\n                                    <div class=\"grid-item elementor-teambox-item\">\n\n                        \n                        <div class=\"team-content\">\n                            <div class=\"team-caption\">\n                                                                    <div class=\"team-job\">Consultant v\u00e2nz\u0103ri<\/div>\n                                \n                                                                    <h6 class=\"team-name\">Timea Cristian<\/h6>\n                                                            <\/div>\n\n                                                            <div class=\"team-image-wrapper\">\n                                                <div class=\"team-image\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"1260\" height=\"1260\" src=\"https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/Timea.jpg\" class=\"attachment-full size-full wp-image-10604\" alt=\"\" srcset=\"https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/Timea.jpg 1260w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/Timea-300x300.jpg 300w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/Timea-1024x1024.jpg 1024w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/Timea-150x150.jpg 150w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/Timea-768x768.jpg 768w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/Timea-800x800.jpg 800w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/Timea-1000x1000.jpg 1000w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/Timea-100x100.jpg 100w\" sizes=\"(max-width: 1260px) 100vw, 1260px\" \/>            <\/div>\n                                                    <div class=\"team-box-socials-wrapper\">\n            <div class=\"team-icon-socials\">\n                <ul>\n                                                                        <li class=\"social\">\n                                <a href=\"https:\/\/www.facebook.com\/opalwordpress\">\n                                    <i class=\"eyecazi-icon-facebook\"><\/i>\n                                <\/a>\n                            <\/li>\n                                                                                                <li class=\"social\">\n                                <a href=\"https:\/\/twitter.com\/opalwordpress\">\n                                    <i class=\"eyecazi-icon-twitter-x\"><\/i>\n                                <\/a>\n                            <\/li>\n                                                                                                <li class=\"social\">\n                                <a href=\"https:\/\/www.instagram.com\/user\/WPOpalTheme\">\n                                    <i class=\"eyecazi-icon-instagram\"><\/i>\n                                <\/a>\n                            <\/li>\n                                                                                                <li class=\"social\">\n                                <a href=\"https:\/\/vn.linkedin.com\/company\/wpopal\">\n                                    <i class=\"eyecazi-icon-linkedin\"><\/i>\n                                <\/a>\n                            <\/li>\n                                                            <\/ul>\n            <\/div>\n        <\/div>\n                                        <\/div>\n                            \n                            <div class=\"team-description\">\n                                \n                                        <div class=\"more-link-wrap\">\n            <a class=\"more-link effect-button-link\" href=\"#\">\n                                    <span class=\"elementor-button-content-wrapper content-wrapper\">\n                    <span class=\"elementor-button-text\">\n                        <span>View Profile<\/span>\n                    <\/span>\n                    <span class=\"button-icon\">\n                        <i class=\"eyecazi-icon-arrow-right\" aria-hidden=\"true\"><\/i>\n                    <\/span>\n                <\/span>\n                                    <span class=\"elementor-button-content-wrapper content-wrapper-hover\">\n                    <span class=\"elementor-button-text\">\n                        <span>View Profile<\/span>\n                    <\/span>\n                    <span class=\"button-icon\">\n                        <i class=\"eyecazi-icon-arrow-right\" aria-hidden=\"true\"><\/i>\n                    <\/span>\n                <\/span>\n                            <\/a>\n        <\/div>\n    \n                                                            <\/div>\n                        <\/div>\n                    <\/div>\n                                    <div class=\"grid-item elementor-teambox-item\">\n\n                        \n                        <div class=\"team-content\">\n                            <div class=\"team-caption\">\n                                                                    <div class=\"team-job\">Consultant v\u00e2nz\u0103ri<\/div>\n                                \n                                                                    <h6 class=\"team-name\">Diana Mihaela Acatinc\u0103i<\/h6>\n                                                            <\/div>\n\n                                                            <div class=\"team-image-wrapper\">\n                                                <div class=\"team-image\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"1260\" height=\"1260\" src=\"https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/BestOptic_Team2.jpg\" class=\"attachment-full size-full wp-image-11922\" alt=\"\" srcset=\"https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/BestOptic_Team2.jpg 1260w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/BestOptic_Team2-300x300.jpg 300w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/BestOptic_Team2-1024x1024.jpg 1024w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/BestOptic_Team2-150x150.jpg 150w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/BestOptic_Team2-768x768.jpg 768w\" sizes=\"(max-width: 1260px) 100vw, 1260px\" \/>            <\/div>\n                                                    <div class=\"team-box-socials-wrapper\">\n            <div class=\"team-icon-socials\">\n                <ul>\n                                                                        <li class=\"social\">\n                                <a href=\"https:\/\/www.facebook.com\/opalwordpress\">\n                                    <i class=\"eyecazi-icon-facebook\"><\/i>\n                                <\/a>\n                            <\/li>\n                                                                                                <li class=\"social\">\n                                <a href=\"https:\/\/twitter.com\/opalwordpress\">\n                                    <i class=\"eyecazi-icon-twitter-x\"><\/i>\n                                <\/a>\n                            <\/li>\n                                                                                                <li class=\"social\">\n                                <a href=\"https:\/\/www.instagram.com\/user\/WPOpalTheme\">\n                                    <i class=\"eyecazi-icon-instagram\"><\/i>\n                                <\/a>\n                            <\/li>\n                                                                                                <li class=\"social\">\n                                <a href=\"https:\/\/vn.linkedin.com\/company\/wpopal\">\n                                    <i class=\"eyecazi-icon-linkedin\"><\/i>\n                                <\/a>\n                            <\/li>\n                                                            <\/ul>\n            <\/div>\n        <\/div>\n                                        <\/div>\n                            \n                            <div class=\"team-description\">\n                                \n                                        <div class=\"more-link-wrap\">\n            <a class=\"more-link effect-button-link\" href=\"#\">\n                                    <span class=\"elementor-button-content-wrapper content-wrapper\">\n                    <span class=\"elementor-button-text\">\n                        <span>View Profile<\/span>\n                    <\/span>\n                    <span class=\"button-icon\">\n                        <i class=\"eyecazi-icon-arrow-right\" aria-hidden=\"true\"><\/i>\n                    <\/span>\n                <\/span>\n                                    <span class=\"elementor-button-content-wrapper content-wrapper-hover\">\n                    <span class=\"elementor-button-text\">\n                        <span>View Profile<\/span>\n                    <\/span>\n                    <span class=\"button-icon\">\n                        <i class=\"eyecazi-icon-arrow-right\" aria-hidden=\"true\"><\/i>\n                    <\/span>\n                <\/span>\n                            <\/a>\n        <\/div>\n    \n                                                            <\/div>\n                        <\/div>\n                    <\/div>\n                                    <div class=\"grid-item elementor-teambox-item\">\n\n                        \n                        <div class=\"team-content\">\n                            <div class=\"team-caption\">\n                                                                    <div class=\"team-job\">Consultant v\u00e2nz\u0103ri<\/div>\n                                \n                                                                    <h6 class=\"team-name\">Cristina Baciu<\/h6>\n                                                            <\/div>\n\n                                                            <div class=\"team-image-wrapper\">\n                                                <div class=\"team-image\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"1260\" height=\"1260\" src=\"https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/BestOptic_Team1.png\" class=\"attachment-full size-full wp-image-10585\" alt=\"\" srcset=\"https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/BestOptic_Team1.png 1260w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/BestOptic_Team1-300x300.png 300w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/BestOptic_Team1-1024x1024.png 1024w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/BestOptic_Team1-150x150.png 150w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/BestOptic_Team1-768x768.png 768w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/BestOptic_Team1-800x800.png 800w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/BestOptic_Team1-1000x1000.png 1000w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/BestOptic_Team1-100x100.png 100w\" sizes=\"(max-width: 1260px) 100vw, 1260px\" \/>            <\/div>\n                                                    <div class=\"team-box-socials-wrapper\">\n            <div class=\"team-icon-socials\">\n                <ul>\n                                                                        <li class=\"social\">\n                                <a href=\"https:\/\/www.facebook.com\/opalwordpress\">\n                                    <i class=\"eyecazi-icon-facebook\"><\/i>\n                                <\/a>\n                            <\/li>\n                                                                                                <li class=\"social\">\n                                <a href=\"https:\/\/twitter.com\/opalwordpress\">\n                                    <i class=\"eyecazi-icon-twitter-x\"><\/i>\n                                <\/a>\n                            <\/li>\n                                                                                                <li class=\"social\">\n                                <a href=\"https:\/\/www.instagram.com\/user\/WPOpalTheme\">\n                                    <i class=\"eyecazi-icon-instagram\"><\/i>\n                                <\/a>\n                            <\/li>\n                                                                                                <li class=\"social\">\n                                <a href=\"https:\/\/vn.linkedin.com\/company\/wpopal\">\n                                    <i class=\"eyecazi-icon-linkedin\"><\/i>\n                                <\/a>\n                            <\/li>\n                                                            <\/ul>\n            <\/div>\n        <\/div>\n                                        <\/div>\n                            \n                            <div class=\"team-description\">\n                                \n                                        <div class=\"more-link-wrap\">\n            <a class=\"more-link effect-button-link\" href=\"#\">\n                                    <span class=\"elementor-button-content-wrapper content-wrapper\">\n                    <span class=\"elementor-button-text\">\n                        <span>View Profile<\/span>\n                    <\/span>\n                    <span class=\"button-icon\">\n                        <i class=\"eyecazi-icon-arrow-right\" aria-hidden=\"true\"><\/i>\n                    <\/span>\n                <\/span>\n                                    <span class=\"elementor-button-content-wrapper content-wrapper-hover\">\n                    <span class=\"elementor-button-text\">\n                        <span>View Profile<\/span>\n                    <\/span>\n                    <span class=\"button-icon\">\n                        <i class=\"eyecazi-icon-arrow-right\" aria-hidden=\"true\"><\/i>\n                    <\/span>\n                <\/span>\n                            <\/a>\n        <\/div>\n    \n                                                            <\/div>\n                        <\/div>\n                    <\/div>\n                                    <div class=\"grid-item elementor-teambox-item\">\n\n                        \n                        <div class=\"team-content\">\n                            <div class=\"team-caption\">\n                                                                    <div class=\"team-job\">Consultant v\u00e2nz\u0103ri<\/div>\n                                \n                                                                    <h6 class=\"team-name\">Valentina Rusu<\/h6>\n                                                            <\/div>\n\n                                                            <div class=\"team-image-wrapper\">\n                                                <div class=\"team-image\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"1260\" height=\"1260\" src=\"https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/BestOptic_Tean9.png\" class=\"attachment-full size-full wp-image-10593\" alt=\"\" srcset=\"https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/BestOptic_Tean9.png 1260w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/BestOptic_Tean9-300x300.png 300w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/BestOptic_Tean9-1024x1024.png 1024w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/BestOptic_Tean9-150x150.png 150w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/BestOptic_Tean9-768x768.png 768w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/BestOptic_Tean9-800x800.png 800w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/BestOptic_Tean9-1000x1000.png 1000w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/BestOptic_Tean9-100x100.png 100w\" sizes=\"(max-width: 1260px) 100vw, 1260px\" \/>            <\/div>\n                                                    <div class=\"team-box-socials-wrapper\">\n            <div class=\"team-icon-socials\">\n                <ul>\n                                                                        <li class=\"social\">\n                                <a href=\"https:\/\/www.facebook.com\/opalwordpress\">\n                                    <i class=\"eyecazi-icon-facebook\"><\/i>\n                                <\/a>\n                            <\/li>\n                                                                                                <li class=\"social\">\n                                <a href=\"https:\/\/twitter.com\/opalwordpress\">\n                                    <i class=\"eyecazi-icon-twitter-x\"><\/i>\n                                <\/a>\n                            <\/li>\n                                                                                                <li class=\"social\">\n                                <a href=\"https:\/\/www.instagram.com\/user\/WPOpalTheme\">\n                                    <i class=\"eyecazi-icon-instagram\"><\/i>\n                                <\/a>\n                            <\/li>\n                                                                                                <li class=\"social\">\n                                <a href=\"https:\/\/vn.linkedin.com\/company\/wpopal\">\n                                    <i class=\"eyecazi-icon-linkedin\"><\/i>\n                                <\/a>\n                            <\/li>\n                                                            <\/ul>\n            <\/div>\n        <\/div>\n                                        <\/div>\n                            \n                            <div class=\"team-description\">\n                                \n                                        <div class=\"more-link-wrap\">\n            <a class=\"more-link effect-button-link\" href=\"#\">\n                                    <span class=\"elementor-button-content-wrapper content-wrapper\">\n                    <span class=\"elementor-button-text\">\n                        <span>View Profile<\/span>\n                    <\/span>\n                    <span class=\"button-icon\">\n                        <i class=\"eyecazi-icon-arrow-right\" aria-hidden=\"true\"><\/i>\n                    <\/span>\n                <\/span>\n                                    <span class=\"elementor-button-content-wrapper content-wrapper-hover\">\n                    <span class=\"elementor-button-text\">\n                        <span>View Profile<\/span>\n                    <\/span>\n                    <span class=\"button-icon\">\n                        <i class=\"eyecazi-icon-arrow-right\" aria-hidden=\"true\"><\/i>\n                    <\/span>\n                <\/span>\n                            <\/a>\n        <\/div>\n    \n                                                            <\/div>\n                        <\/div>\n                    <\/div>\n                            <\/div>\n        <\/div>\n\n                        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-11bcc84 animated-fast e-flex e-con-boxed elementor-invisible e-con e-parent\" data-id=\"11bcc84\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;opal-move-up&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-ed59124 e-con-full e-flex e-con e-child\" data-id=\"ed59124\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-e0d5a76 e-con-full e-flex e-con e-child\" data-id=\"e0d5a76\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b296fd7 animated-fast elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-invisible elementor-widget elementor-widget-icon-list\" data-id=\"b296fd7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;opal-move-up&quot;}\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eyecazi-icon- eyecazi-icon-icon-cross\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Cabinete Best Optic <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c61e692 elementor-widget__width-initial animated-fast elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"c61e692\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;opal-move-up&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Unde ne vedem<br>la ochi?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d5403f4 e-con-full e-flex e-con e-child\" data-id=\"d5403f4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9fd1ef1 elementor-widget__width-initial animated-fast elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"9fd1ef1\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;opal-move-up&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Ai mai multe cabinete \u00een Bra\u0219ov \u0219i Codlea din care po\u021bi alege, \u00een func\u021bie de unde locuie\u0219ti \u0219i de ce ai nevoie: consult, lentile de contact, controale sau montaj. <\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5596643 elementor-widget__width-initial elementor-widget-tablet_extra__width-initial animated-fast elementor-invisible elementor-widget elementor-widget-counter\" data-id=\"5596643\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;opal-move-up&quot;}\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">Cabinete <\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"1000\" data-to-value=\"4\" data-from-value=\"0\" data-delimiter=\",\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-40de071 elementor-widget__width-inherit elementor-portfolio-style-1 elementor-portfolio-style-effect-yes overflow-to-none elementor-widget elementor-widget-eyecazi-portfolios\" data-id=\"40de071\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:3,&quot;spaceBetween&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:30,&quot;sizes&quot;:[]},&quot;spaceBetween_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;spaceBetween_tablet_extra&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;spaceBetween_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;spaceBetween_mobile_extra&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;spaceBetween_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;swiper_overflow&quot;:&quot;none&quot;,&quot;navigation&quot;:&quot;none&quot;,&quot;enable_scrollbar&quot;:&quot;no&quot;,&quot;allowTouchMove&quot;:&quot;yes&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500}\" data-widget_type=\"eyecazi-portfolios.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"elementor-portfolio-wrapper\">\n            <div class=\"d-grid\">\n                                    <div class=\"grid-item\">\n                        <div class=\"portfolio-item portfolio-style-1\">\n    <div class=\"portfolio-item-inner\">\n        <div class=\"portfolio-post-thumbnail\">\n                            <div class=\"portfolio-image\">\n                    <img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1710\" src=\"https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/DSC09765-Edit-scaled.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/DSC09765-Edit-scaled.jpg 2560w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/DSC09765-Edit-300x200.jpg 300w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/DSC09765-Edit-1024x684.jpg 1024w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/DSC09765-Edit-768x513.jpg 768w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/DSC09765-Edit-1536x1026.jpg 1536w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/DSC09765-Edit-2048x1368.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>                <\/div>\n                    <\/div><!-- .post-thumbnail -->\n        <div class=\"portfolio-content\">\n            <div class=\"portfolio-content-inner\">\n                <div class=\"portfolio-meta\">\n                    <div class=\"portfolio-category\"><a href=\"https:\/\/bestoptic.ro\/en\/portfolio-cat\/bd-15-noiembrie-nr-69-et-1\/\" rel=\"tag\">Bd. 15 Noiembrie, Nr. 69, Et. 1<\/a><\/div>                <\/div>\n                <h4 class=\"portfolio-title omega\"><a href=\"https:\/\/bestoptic.ro\/en\/portfolios\/boblue\/\">Best Optic Blue<\/a><\/h4>\n                <div class=\"portfolio-excerpt\"> <p>Experien\u021b\u0103 360 grade<\/p>\n<\/div>\n                <div class=\"more-link-wrap\">\n                    <a class=\"more-link effect-button-link\" href=\"https:\/\/bestoptic.ro\/en\/portfolios\/boblue\/\">\n                        <span class=\"content-wrapper\">\n                            <span class=\"button-text\">Learn More<\/span>\n                            <span class=\"button-icon\"><i class=\"eyecazi-icon-arrow-right\"><\/i><\/span>\n                        <\/span>\n                        <span class=\"content-wrapper-hover\">\n                            <span class=\"button-text\">Learn More<\/span>\n                            <span class=\"button-icon\"><i class=\"eyecazi-icon-arrow-right\"><\/i><\/span>\n                        <\/span>\n                    <\/a>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                    <\/div>\n                                        <div class=\"grid-item\">\n                        <div class=\"portfolio-item portfolio-style-1\">\n    <div class=\"portfolio-item-inner\">\n        <div class=\"portfolio-post-thumbnail\">\n                            <div class=\"portfolio-image\">\n                    <img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1710\" src=\"https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/DSC09740-Edit-scaled.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/DSC09740-Edit-scaled.jpg 2560w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/DSC09740-Edit-300x200.jpg 300w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/DSC09740-Edit-1024x684.jpg 1024w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/DSC09740-Edit-768x513.jpg 768w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/DSC09740-Edit-1536x1026.jpg 1536w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/DSC09740-Edit-2048x1368.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>                <\/div>\n                    <\/div><!-- .post-thumbnail -->\n        <div class=\"portfolio-content\">\n            <div class=\"portfolio-content-inner\">\n                <div class=\"portfolio-meta\">\n                    <div class=\"portfolio-category\"><a href=\"https:\/\/bestoptic.ro\/en\/portfolio-cat\/bd-15-noiembrie-nr-69-et-2\/\" rel=\"tag\">Bd. 15 Noiembrie, Nr. 69, Et. 2<\/a><\/div>                <\/div>\n                <h4 class=\"portfolio-title omega\"><a href=\"https:\/\/bestoptic.ro\/en\/portfolios\/bolentile\/\">Best Optic Lentile de Contact<\/a><\/h4>\n                <div class=\"portfolio-excerpt\"> <p>Primul centrul dedicat lentilelor de contact din Europa<\/p>\n<\/div>\n                <div class=\"more-link-wrap\">\n                    <a class=\"more-link effect-button-link\" href=\"https:\/\/bestoptic.ro\/en\/portfolios\/bolentile\/\">\n                        <span class=\"content-wrapper\">\n                            <span class=\"button-text\">Learn More<\/span>\n                            <span class=\"button-icon\"><i class=\"eyecazi-icon-arrow-right\"><\/i><\/span>\n                        <\/span>\n                        <span class=\"content-wrapper-hover\">\n                            <span class=\"button-text\">Learn More<\/span>\n                            <span class=\"button-icon\"><i class=\"eyecazi-icon-arrow-right\"><\/i><\/span>\n                        <\/span>\n                    <\/a>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                    <\/div>\n                                        <div class=\"grid-item\">\n                        <div class=\"portfolio-item portfolio-style-1\">\n    <div class=\"portfolio-item-inner\">\n        <div class=\"portfolio-post-thumbnail\">\n                            <div class=\"portfolio-image\">\n                    <img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/DSC09023-Edit-scaled.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/DSC09023-Edit-scaled.jpg 2560w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/DSC09023-Edit-300x200.jpg 300w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/DSC09023-Edit-1024x683.jpg 1024w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/DSC09023-Edit-768x512.jpg 768w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/DSC09023-Edit-1536x1024.jpg 1536w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/DSC09023-Edit-2048x1365.jpg 2048w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/DSC09023-Edit-800x533.jpg 800w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/DSC09023-Edit-1000x667.jpg 1000w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>                <\/div>\n                    <\/div><!-- .post-thumbnail -->\n        <div class=\"portfolio-content\">\n            <div class=\"portfolio-content-inner\">\n                <div class=\"portfolio-meta\">\n                    <div class=\"portfolio-category\"><a href=\"https:\/\/bestoptic.ro\/en\/portfolio-cat\/bd-al-vlahuta-nr-32\/\" rel=\"tag\">Bd. Al. Vlahu\u021b\u0103, Nr. 32<\/a><\/div>                <\/div>\n                <h4 class=\"portfolio-title omega\"><a href=\"https:\/\/bestoptic.ro\/en\/portfolios\/bovlahuta\/\">Best Optic Vlahu\u021b\u0103<\/a><\/h4>\n                <div class=\"portfolio-excerpt\"> <p>Expertul t\u0103u \u00een lentile progresive<\/p>\n<\/div>\n                <div class=\"more-link-wrap\">\n                    <a class=\"more-link effect-button-link\" href=\"https:\/\/bestoptic.ro\/en\/portfolios\/bovlahuta\/\">\n                        <span class=\"content-wrapper\">\n                            <span class=\"button-text\">Learn More<\/span>\n                            <span class=\"button-icon\"><i class=\"eyecazi-icon-arrow-right\"><\/i><\/span>\n                        <\/span>\n                        <span class=\"content-wrapper-hover\">\n                            <span class=\"button-text\">Learn More<\/span>\n                            <span class=\"button-icon\"><i class=\"eyecazi-icon-arrow-right\"><\/i><\/span>\n                        <\/span>\n                    <\/a>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                    <\/div>\n                                        <div class=\"grid-item\">\n                        <div class=\"portfolio-item portfolio-style-1\">\n    <div class=\"portfolio-item-inner\">\n        <div class=\"portfolio-post-thumbnail\">\n                            <div class=\"portfolio-image\">\n                    <img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1852\" src=\"https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/DSC09539-Edit-scaled.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/DSC09539-Edit-scaled.jpg 2560w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/DSC09539-Edit-300x217.jpg 300w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/DSC09539-Edit-1024x741.jpg 1024w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/DSC09539-Edit-768x556.jpg 768w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/DSC09539-Edit-1536x1111.jpg 1536w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/DSC09539-Edit-2048x1481.jpg 2048w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/DSC09539-Edit-800x579.jpg 800w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/DSC09539-Edit-1000x723.jpg 1000w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>                <\/div>\n                    <\/div><!-- .post-thumbnail -->\n        <div class=\"portfolio-content\">\n            <div class=\"portfolio-content-inner\">\n                <div class=\"portfolio-meta\">\n                    <div class=\"portfolio-category\"><a href=\"https:\/\/bestoptic.ro\/en\/portfolio-cat\/str-lunga-nr-141-codlea\/\" rel=\"tag\">Str. Lung\u0103, Nr. 141, Codlea<\/a><\/div>                <\/div>\n                <h4 class=\"portfolio-title omega\"><a href=\"https:\/\/bestoptic.ro\/en\/portfolios\/bocodlea\/\">Best Optic Codlea<\/a><\/h4>\n                <div class=\"portfolio-excerpt\"> <p>Consultul t\u0103u complet, aproape de cas\u0103<\/p>\n<\/div>\n                <div class=\"more-link-wrap\">\n                    <a class=\"more-link effect-button-link\" href=\"https:\/\/bestoptic.ro\/en\/portfolios\/bocodlea\/\">\n                        <span class=\"content-wrapper\">\n                            <span class=\"button-text\">Learn More<\/span>\n                            <span class=\"button-icon\"><i class=\"eyecazi-icon-arrow-right\"><\/i><\/span>\n                        <\/span>\n                        <span class=\"content-wrapper-hover\">\n                            <span class=\"button-text\">Learn More<\/span>\n                            <span class=\"button-icon\"><i class=\"eyecazi-icon-arrow-right\"><\/i><\/span>\n                        <\/span>\n                    <\/a>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                    <\/div>\n                                        <div class=\"grid-item\">\n                        <div class=\"portfolio-item portfolio-style-1\">\n    <div class=\"portfolio-item-inner\">\n        <div class=\"portfolio-post-thumbnail\">\n                            <div class=\"portfolio-image\">\n                    <img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1710\" src=\"https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/DSC09752-Edit-scaled.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/DSC09752-Edit-scaled.jpg 2560w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/DSC09752-Edit-300x200.jpg 300w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/DSC09752-Edit-1024x684.jpg 1024w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/DSC09752-Edit-768x513.jpg 768w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/DSC09752-Edit-1536x1026.jpg 1536w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/08\/DSC09752-Edit-2048x1368.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>                <\/div>\n                    <\/div><!-- .post-thumbnail -->\n        <div class=\"portfolio-content\">\n            <div class=\"portfolio-content-inner\">\n                <div class=\"portfolio-meta\">\n                    <div class=\"portfolio-category\"><a href=\"https:\/\/bestoptic.ro\/en\/portfolio-cat\/bd-15-noiembrie-nr-69-et-2\/\" rel=\"tag\">Bd. 15 Noiembrie, Nr. 69, Et. 2<\/a><\/div>                <\/div>\n                <h4 class=\"portfolio-title omega\"><a href=\"https:\/\/bestoptic.ro\/en\/portfolios\/bolab\/\">Best Optic Lab<\/a><\/h4>\n                <div class=\"portfolio-excerpt\"> <p>Atelierul \u00een care prind form\u0103 ochelarii t\u0103i<\/p>\n<\/div>\n                <div class=\"more-link-wrap\">\n                    <a class=\"more-link effect-button-link\" href=\"https:\/\/bestoptic.ro\/en\/portfolios\/bolab\/\">\n                        <span class=\"content-wrapper\">\n                            <span class=\"button-text\">Learn More<\/span>\n                            <span class=\"button-icon\"><i class=\"eyecazi-icon-arrow-right\"><\/i><\/span>\n                        <\/span>\n                        <span class=\"content-wrapper-hover\">\n                            <span class=\"button-text\">Learn More<\/span>\n                            <span class=\"button-icon\"><i class=\"eyecazi-icon-arrow-right\"><\/i><\/span>\n                        <\/span>\n                    <\/a>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                    <\/div>\n                                <\/div>\n\n        <\/div>\n                \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b1c5b00 e-con-full e-flex e-con e-child\" data-id=\"b1c5b00\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-88124f6 e-flex e-con-boxed e-con e-child\" data-id=\"88124f6\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-0188736 e-con-full e-flex e-con e-child\" data-id=\"0188736\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d65ae3d animated-fast elementor-widget__width-initial elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-invisible elementor-widget elementor-widget-icon-list\" data-id=\"d65ae3d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;opal-move-up&quot;}\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eyecazi-icon- eyecazi-icon-icon-cross\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Vezi prin ochii lor<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ce7c7f2 elementor-widget__width-initial animated-fast elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"ce7c7f2\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;opal-move-up&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ce spun cei care au fost deja la noi\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0991542 elementor-widget__width-initial animated-fast elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"0991542\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;opal-move-up&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Recenziile lor te ajut\u0103 s\u0103 decizi dac\u0103 Best Optic este locul potrivit pentru ochii t\u0103i.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3fe567f e-con-full e-flex e-con e-child\" data-id=\"3fe567f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-15ed564 elementor-widget__width-initial animated-fast elementor-invisible elementor-widget elementor-widget-counter\" data-id=\"15ed564\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;opal-move-up&quot;}\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"1000\" data-to-value=\"5\" data-from-value=\"0\" data-delimiter=\",\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0f10724 animated-fast elementor-view-default elementor-invisible elementor-widget elementor-widget-icon\" data-id=\"0f10724\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;opal-move-left&quot;}\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"eyecazi-icon- eyecazi-icon-star\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a2c4537 animated-fast elementor-widget__width-initial elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"a2c4537\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;opal-move-up&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Peste 5.000 de <span style=\"font-weight: 400;\">pacien\u021bi mul\u021bumi\u021bi<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-018caf5 elementor-absolute elementor-widget elementor-widget-image\" data-id=\"018caf5\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/demo2wpopal.b-cdn.net\/eyecazi\/wp-content\/uploads\/2025\/09\/h4_deco-right.svg\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5e4179f e-con-full e-flex e-con e-child\" data-id=\"5e4179f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-7b184e4 e-con-full animated-fast e-flex elementor-invisible e-con e-child\" data-id=\"7b184e4\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;opal-scale-up&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-caff4fd alignment-left overflow-to-none elementor-pagination-position-outside elementor-widget elementor-widget-eyecazi-testimonials\" data-id=\"caff4fd\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;dots&quot;,&quot;spaceBetween&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:30,&quot;sizes&quot;:[]},&quot;spaceBetween_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;spaceBetween_tablet_extra&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;spaceBetween_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;spaceBetween_mobile_extra&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;spaceBetween_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;swiper_overflow&quot;:&quot;none&quot;,&quot;navigation_type&quot;:&quot;bullets&quot;,&quot;enable_scrollbar&quot;:&quot;no&quot;,&quot;allowTouchMove&quot;:&quot;yes&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"eyecazi-testimonials.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t            <div class=\"elementor-testimonial-item-wrapper eyecazi-swiper swiper \" dir=\"ltr\">\n                <div class=\"swiper-wrapper\">\n                                            <div class=\"grid-item swiper-slide elementor-testimonial-item\">\n                            <div class=\"testimonial-content elementor-repeater-item-1e7904b\">\n                                                                <div class=\"wrap_content\">\n                                <div class=\"elementor-testimonial-rating\"><i aria-hidden=\"true\" class=\"eyecazi-icon-star\"><\/i><i aria-hidden=\"true\" class=\"eyecazi-icon-star\"><\/i><i aria-hidden=\"true\" class=\"eyecazi-icon-star\"><\/i><i aria-hidden=\"true\" class=\"eyecazi-icon-star\"><\/i><i aria-hidden=\"true\" class=\"eyecazi-icon-star\"><\/i><\/div>                                \n                                                                    <div class=\"content\"><p>Best OPTIC Blue este, categoric, locul \u00een care vei fi tratat cu bl\u00e2nde\u021be, cu empatie \u0219i profesionalism.<br \/>Odat\u0103 \u00eentrat pe m\u00e2na echipei Best OPTIC Blue, st\u0103rile de inconfort, \u00eengrijorare sau stress care, \u00een mod firesc, \u00eenso\u021besc orice afec\u021biune medical\u0103 dispar ca prin minune.<br \/>Recomand Best OPTIC Blue f\u0103r\u0103 rezerve!<\/p><\/div>\n                                                                <\/div>\n                                    <div class=\"details\">\n                                                                                <div class=\"details-info\">\n                                            <span class=\"name\">Silvia Ghia<\/span>                                                                                            <span class=\"job\">Best Opic Blue<\/span>\n                                                                                    <\/div>\n                                    <\/div>\n\n\n                            <\/div>\n                        <\/div>\n                                            <div class=\"grid-item swiper-slide elementor-testimonial-item\">\n                            <div class=\"testimonial-content elementor-repeater-item-6b3c3e0\">\n                                                                <div class=\"wrap_content\">\n                                <div class=\"elementor-testimonial-rating\"><i aria-hidden=\"true\" class=\"eyecazi-icon-star\"><\/i><i aria-hidden=\"true\" class=\"eyecazi-icon-star\"><\/i><i aria-hidden=\"true\" class=\"eyecazi-icon-star\"><\/i><i aria-hidden=\"true\" class=\"eyecazi-icon-star\"><\/i><i aria-hidden=\"true\" class=\"eyecazi-icon-star\"><\/i><\/div>                                \n                                                                    <div class=\"content\"><p>Best Optic, pot spune \"the Best\", personal extraordinar, mul\u021bumesc doamnei Doctor Moldovan, un medic exemplar, recomand tuturor , av\u00e2nd \u0219i o aparatur\u0103 de \u00eenalt\u0103 performanta<\/p><\/div>\n                                                                <\/div>\n                                    <div class=\"details\">\n                                                                                <div class=\"details-info\">\n                                            <span class=\"name\">Geo Lupu<\/span>                                                                                            <span class=\"job\">Best Opic Blue<\/span>\n                                                                                    <\/div>\n                                    <\/div>\n\n\n                            <\/div>\n                        <\/div>\n                                            <div class=\"grid-item swiper-slide elementor-testimonial-item\">\n                            <div class=\"testimonial-content elementor-repeater-item-be458a6\">\n                                                                <div class=\"wrap_content\">\n                                <div class=\"elementor-testimonial-rating\"><i aria-hidden=\"true\" class=\"eyecazi-icon-star\"><\/i><i aria-hidden=\"true\" class=\"eyecazi-icon-star\"><\/i><i aria-hidden=\"true\" class=\"eyecazi-icon-star\"><\/i><i aria-hidden=\"true\" class=\"eyecazi-icon-star\"><\/i><i aria-hidden=\"true\" class=\"eyecazi-icon-star\"><\/i><\/div>                                \n                                                                    <div class=\"content\"><p>Acela\u0219i profesionalism cu care am fost deja obi\u0219nui\u021bi.<br \/>Mul\u021bumim pentru toat\u0103 implicarea \u0219i dedicarea ce o rev\u0103rsa\u021bi asupra tuturor persoanelor ce v\u0103 trec pragul.<\/p><p>Vom reveni de fiecare dat\u0103 cu pl\u0103cere \u0219i \u00eencredere!<\/p><\/div>\n                                                                <\/div>\n                                    <div class=\"details\">\n                                                                                <div class=\"details-info\">\n                                            <span class=\"name\">Cristina Mesco<\/span>                                                                                            <span class=\"job\">Best Optic Blue<\/span>\n                                                                                    <\/div>\n                                    <\/div>\n\n\n                            <\/div>\n                        <\/div>\n                                            <div class=\"grid-item swiper-slide elementor-testimonial-item\">\n                            <div class=\"testimonial-content elementor-repeater-item-eb8c67f\">\n                                                                <div class=\"wrap_content\">\n                                <div class=\"elementor-testimonial-rating\"><i aria-hidden=\"true\" class=\"eyecazi-icon-star\"><\/i><i aria-hidden=\"true\" class=\"eyecazi-icon-star\"><\/i><i aria-hidden=\"true\" class=\"eyecazi-icon-star\"><\/i><i aria-hidden=\"true\" class=\"eyecazi-icon-star\"><\/i><i aria-hidden=\"true\" class=\"eyecazi-icon-star\"><\/i><\/div>                                \n                                                                    <div class=\"content\"><p>Singurii care au reusit sa imi faca lentile potrivite pentru mine.<br \/>Am o dioptrie mai ciudata dar cei de la Best Optic au reusit unde altii au esuat.<br \/>Recomand!<\/p><\/div>\n                                                                <\/div>\n                                    <div class=\"details\">\n                                                                                <div class=\"details-info\">\n                                            <span class=\"name\">Matei Gardu<\/span>                                                                                            <span class=\"job\">Best Optic Vlahu\u021b\u0103<\/span>\n                                                                                    <\/div>\n                                    <\/div>\n\n\n                            <\/div>\n                        <\/div>\n                                            <div class=\"grid-item swiper-slide elementor-testimonial-item\">\n                            <div class=\"testimonial-content elementor-repeater-item-3d4ebd5\">\n                                                                <div class=\"wrap_content\">\n                                <div class=\"elementor-testimonial-rating\"><i aria-hidden=\"true\" class=\"eyecazi-icon-star\"><\/i><i aria-hidden=\"true\" class=\"eyecazi-icon-star\"><\/i><i aria-hidden=\"true\" class=\"eyecazi-icon-star\"><\/i><i aria-hidden=\"true\" class=\"eyecazi-icon-star\"><\/i><i aria-hidden=\"true\" class=\"eyecazi-icon-star\"><\/i><\/div>                                \n                                                                    <div class=\"content\"><p>For\u021be mul\u021bumit\u0103, personalul este deosebit, un comportament minunat fa\u021b\u0103 de copii \u0219i de adul\u021bi, totul este punctual (f\u0103r\u0103 timp de a\u0219teptare ), aparatur\u0103 minunat\u0103, \u0219i o atmosfer\u0103 pl\u0103cut\u0103, sunte\u021bi minuna\u021bi, felicit\u0103ri!<\/p><\/div>\n                                                                <\/div>\n                                    <div class=\"details\">\n                                                                                <div class=\"details-info\">\n                                            <span class=\"name\">Somu Delia<\/span>                                                                                            <span class=\"job\">Best Optic Blue<\/span>\n                                                                                    <\/div>\n                                    <\/div>\n\n\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                        <div class=\"swiper-pagination\"><\/div>\n                \n            \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fb13389 elementor-view-stacked elementor-absolute elementor-shape-circle elementor-widget elementor-widget-icon\" data-id=\"fb13389\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"eyecazi-icon- eyecazi-icon-quotes\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bd24231 elementor-widget__width-initial elementor-absolute elementor-hidden-mobile animated-fast elementor-invisible elementor-widget elementor-widget-image\" data-id=\"bd24231\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;,&quot;_animation&quot;:&quot;opal-move-left&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1536\" src=\"https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/12\/DSC00092-scaled-e1766152771126.jpg\" class=\"attachment-full size-full wp-image-11297\" alt=\"\" srcset=\"https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/12\/DSC00092-scaled-e1766152771126.jpg 2560w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/12\/DSC00092-scaled-e1766152771126-300x180.jpg 300w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/12\/DSC00092-scaled-e1766152771126-1024x614.jpg 1024w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/12\/DSC00092-scaled-e1766152771126-768x461.jpg 768w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/12\/DSC00092-scaled-e1766152771126-1536x922.jpg 1536w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/12\/DSC00092-scaled-e1766152771126-2048x1229.jpg 2048w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/12\/DSC00092-scaled-e1766152771126-800x480.jpg 800w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/12\/DSC00092-scaled-e1766152771126-1000x600.jpg 1000w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-92b4bfa elementor-absolute elementor-widget elementor-widget-image\" data-id=\"92b4bfa\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/demo2wpopal.b-cdn.net\/eyecazi\/wp-content\/uploads\/2025\/09\/h4_deco-left.png\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8d75e7c e-flex e-con-boxed e-con e-parent\" data-id=\"8d75e7c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-e22a301 e-con-full e-flex e-con e-child\" data-id=\"e22a301\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-12ccb29 animated-fast elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-invisible elementor-widget elementor-widget-icon-list\" data-id=\"12ccb29\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;opal-move-up&quot;}\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eyecazi-icon- eyecazi-icon-icon-cross\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Programeaz\u0103-te<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6855713 animated-fast elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"6855713\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;opal-move-up&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">C\u00e2nd ne <br>vedem la ochi?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d1c5bf5 animated-fast elementor-invisible elementor-widget elementor-widget-eyecazi-contactform\" data-id=\"d1c5bf5\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;opal-move-up&quot;}\" data-widget_type=\"eyecazi-contactform.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f155-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"155\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/en\/wp-json\/wp\/v2\/pages\/171#wpcf7-f155-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"155\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.5\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f155-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<div class=\"row\">\n\t<div class=\"column-50\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" autocomplete=\"name\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Nume*\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"column-50\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" autocomplete=\"email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Adres\u0103 email*\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"column-50\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-tel\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Telefon*\" value=\"\" type=\"tel\" name=\"your-tel\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"column-50\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"select-cabinet\"><select class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"select-cabinet\"><option value=\"\">Cabinet<\/option><option value=\"Best Optic Blue\">Best Optic Blue<\/option><option value=\"Best Optic Vlahu\u021b\u0103\">Best Optic Vlahu\u021b\u0103<\/option><option value=\"Best Optic Lentile\">Best Optic Lentile<\/option><option value=\"Best Optic Codlea\">Best Optic Codlea<\/option><\/select><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"column-100 wpcf7-form-desc\">\n\t\t<p>Ai grij\u0103 de s\u0103n\u0103tatea ochilor t\u0103i. Trimite-ne datele talede contact \u0219i \u00ee\u021bi program\u0103m rapid o consulta\u021bie \u00een care g\u0103sim \u00eempreun\u0103 cele mai bune solu\u021bii pentru vederea ta.\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"row\">\n\t<\/div>\n\t<div class=\"column-100\">\n\t\t<div class=\"elementor-widget-eyecazi-button\">\n\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t<p><button type=\"submit\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\"><span class=\"elementor-button-content-wrapper content-wrapper\"><span class=\"elementor-button-text\"><span>Programeaz\u0103-te<\/span><\/span><span class=\"elementor-button-icon\"><i aria-hidden=\"true\" class=\"eyecazi-icon-arrow-right\"><\/i><\/span><\/span><span class=\"elementor-button-content-wrapper content-wrapper-hover\"><span class=\"elementor-button-text\"><span>Programeaz\u0103-te<\/span><\/span><span class=\"elementor-button-icon\"><i aria-hidden=\"true\" class=\"eyecazi-icon-arrow-right\"><\/i><\/span><\/span><\/button>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4d0449e e-con-full e-flex e-con e-child\" data-id=\"4d0449e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-8f00182 e-con-full animated-fast e-flex elementor-invisible e-con e-child\" data-id=\"8f00182\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;opal-move-left&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-153533a elementor-widget elementor-widget-heading\" data-id=\"153533a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Sun\u0103-ne!<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-77eaa89 elementor-view-stacked elementor-position-inline-start elementor-mobile-position-inline-start icon-box-eyecazi-animation-yes elementor-shape-circle elementor-widget elementor-widget-icon-box\" data-id=\"77eaa89\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"tel:+40%20771%20222%20333\" class=\"elementor-icon\" tabindex=\"-1\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"eyecazi-icon- eyecazi-icon-calling\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t0771 222 333\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7304862 elementor-widget__width-initial elementor-absolute elementor-hidden-mobile elementor-widget elementor-widget-image\" data-id=\"7304862\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2157\" height=\"2560\" src=\"https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/12\/DSC00151-Edit-Copy-scaled.jpg\" class=\"attachment-full size-full wp-image-11300\" alt=\"\" srcset=\"https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/12\/DSC00151-Edit-Copy-scaled.jpg 2157w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/12\/DSC00151-Edit-Copy-253x300.jpg 253w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/12\/DSC00151-Edit-Copy-863x1024.jpg 863w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/12\/DSC00151-Edit-Copy-768x911.jpg 768w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/12\/DSC00151-Edit-Copy-1294x1536.jpg 1294w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/12\/DSC00151-Edit-Copy-1726x2048.jpg 1726w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/12\/DSC00151-Edit-Copy-800x949.jpg 800w, https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/12\/DSC00151-Edit-Copy-1000x1187.jpg 1000w\" sizes=\"(max-width: 2157px) 100vw, 2157px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d749fc4 e-con-full e-flex e-con e-parent\" data-id=\"d749fc4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b0b91dc animated-fast elementor-invisible elementor-widget elementor-widget-eyecazi-image-carousel\" data-id=\"b0b91dc\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;opal-move-up&quot;}\" data-widget_type=\"eyecazi-image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div >\n            <div class=\"d-grid\">\n                                    <div class=\"image-carousel-item grid-item\">\n                                                <a class=\"elementor-clickable\">\n                            <div class=\"overlay\"><\/div>\n                            <img decoding=\"async\" src=\"https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/12\/DSC07283-scaled.jpg\" class=\"item-image\"\n                                 alt=\"DSC07283\"\/>\n                            <i aria-hidden=\"true\" class=\"hover-icon eyecazi-icon- eyecazi-icon-instagram\"><\/i>                        <\/a>\n\n                                            <\/div>\n                                    <div class=\"image-carousel-item grid-item\">\n                                                <a class=\"elementor-clickable\">\n                            <div class=\"overlay\"><\/div>\n                            <img decoding=\"async\" src=\"https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/12\/DSC01019-scaled.jpg\" class=\"item-image\"\n                                 alt=\"DSC01019\"\/>\n                            <i aria-hidden=\"true\" class=\"hover-icon eyecazi-icon- eyecazi-icon-instagram\"><\/i>                        <\/a>\n\n                                            <\/div>\n                                    <div class=\"image-carousel-item grid-item\">\n                                                <a class=\"elementor-clickable\">\n                            <div class=\"overlay\"><\/div>\n                            <img decoding=\"async\" src=\"https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/12\/BestOptic-2-scaled.jpg\" class=\"item-image\"\n                                 alt=\"BestOptic (2)\"\/>\n                            <i aria-hidden=\"true\" class=\"hover-icon eyecazi-icon- eyecazi-icon-instagram\"><\/i>                        <\/a>\n\n                                            <\/div>\n                                    <div class=\"image-carousel-item grid-item\">\n                                                <a class=\"elementor-clickable\">\n                            <div class=\"overlay\"><\/div>\n                            <img decoding=\"async\" src=\"https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/12\/DSC07405-Edit-scaled.jpg\" class=\"item-image\"\n                                 alt=\"DSC07405-Edit\"\/>\n                            <i aria-hidden=\"true\" class=\"hover-icon eyecazi-icon- eyecazi-icon-instagram\"><\/i>                        <\/a>\n\n                                            <\/div>\n                                    <div class=\"image-carousel-item grid-item\">\n                                                <a class=\"elementor-clickable\">\n                            <div class=\"overlay\"><\/div>\n                            <img decoding=\"async\" src=\"https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/12\/DSC07274-Edit-scaled.jpg\" class=\"item-image\"\n                                 alt=\"DSC07274-Edit\"\/>\n                            <i aria-hidden=\"true\" class=\"hover-icon eyecazi-icon- eyecazi-icon-instagram\"><\/i>                        <\/a>\n\n                                            <\/div>\n                                    <div class=\"image-carousel-item grid-item\">\n                                                <a class=\"elementor-clickable\">\n                            <div class=\"overlay\"><\/div>\n                            <img decoding=\"async\" src=\"https:\/\/bestoptic.ro\/wp-content\/uploads\/2025\/12\/DSC00969-scaled.jpg\" class=\"item-image\"\n                                 alt=\"DSC00969\"\/>\n                            <i aria-hidden=\"true\" class=\"hover-icon eyecazi-icon- eyecazi-icon-instagram\"><\/i>                        <\/a>\n\n                                            <\/div>\n                            <\/div>\n        <\/div>\n                        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6b7b661 animated-fast elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"6b7b661\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;opal-move-up&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Urm\u0103re\u0219te-ne pe Instagram: @bestoptic.ro<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Cu pasiune pentru vederea ta Tu e\u0219ti punctul nostru de focus Consulta\u021bii complete,g\u00e2ndite \u00een jurul t\u0103u Prime\u0219ti prescrip\u021bii f\u0103cute doar pe baza unor investiga\u021bii detaliate, cu timp dedicat \u021bie, explica\u021bii clare \u0219i consiliere \u00een alegerea ramelor \u0219i lentilelor. Fiecare ochi este privit ca unic, iar solu\u021bia vizual\u0103 este construit\u0103 pentru felul \u00een care \u00ee\u021bi folose\u0219ti [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-171","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/bestoptic.ro\/en\/wp-json\/wp\/v2\/pages\/171","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bestoptic.ro\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/bestoptic.ro\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/bestoptic.ro\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/bestoptic.ro\/en\/wp-json\/wp\/v2\/comments?post=171"}],"version-history":[{"count":166,"href":"https:\/\/bestoptic.ro\/en\/wp-json\/wp\/v2\/pages\/171\/revisions"}],"predecessor-version":[{"id":13330,"href":"https:\/\/bestoptic.ro\/en\/wp-json\/wp\/v2\/pages\/171\/revisions\/13330"}],"wp:attachment":[{"href":"https:\/\/bestoptic.ro\/en\/wp-json\/wp\/v2\/media?parent=171"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}